{"id":171,"date":"2019-05-07T08:00:09","date_gmt":"2019-05-07T06:00:09","guid":{"rendered":"https:\/\/www.stamping-fairies.de\/blog\/?p=171"},"modified":"2022-05-13T14:01:18","modified_gmt":"2022-05-13T12:01:18","slug":"smile","status":"publish","type":"post","link":"https:\/\/www.stamping-fairies.de\/blog\/2019\/05\/07\/smile\/","title":{"rendered":"#SMILE"},"content":{"rendered":"\n<p>Hallo Ihr Lieben!<\/p>\n\n\n\n<p> Kennt Ihr die <a href=\"https:\/\/www.stamping-fairies.de\/montierte-stempel\/mft\/mft-picture-perfect.html\">Picture Perfect Stempel<\/a> aus dem April-Release von MFT? Die  hatten es mir sofort angetan. Denn in diesem Set sind eben auch mal  Tiere wie Hamster, Faultier, Affe. Trotzdem haben es auf meine zweite  Karte mit dem Set die Hunde geschafft.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"734\" height=\"1024\" src=\"https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105626-734x1024.jpg\" alt=\"\" class=\"wp-image-172\" srcset=\"https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105626-734x1024.jpg 734w, https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105626-215x300.jpg 215w, https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105626-768x1071.jpg 768w, https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105626.jpg 1101w\" sizes=\"auto, (max-width: 734px) 100vw, 734px\" \/><\/figure>\n\n\n\n<p> Aus einem St\u00fcck schwarzem Cardstock, das ich etwas kleiner als meine  wei\u00dfe Kartenbasis zugeschnitten habe, habe ich verteilt das #smile aus  dem <a href=\"https:\/\/www.stamping-fairies.de\/stanzen-embossing-folder\/die-namics\/die-namics-captions.html\">Stanzenset #Captions<\/a> ausgestanzt und den Hintergrund dann mit rotem  Cardstock hinterlegt. Da nur das rot ausgestanzte #smile ein wenig fad  wirkte, habe ich dazwischen noch einige Male click mit <a href=\"https:\/\/www.stamping-fairies.de\/stempelzubehoer\/embossingpulver\/ranger\/ranger-embossing-pulver-white-super-fine-detail.html\">wei\u00dfem Embossingpulver <\/a>aufembosst.  Daf\u00fcr habe ich einfach nur das letzte Wort eines der Texte aus dem  Picture Perfect Set abgestempelt. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"594\" height=\"1024\" src=\"https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105634-594x1024.jpg\" alt=\"\" class=\"wp-image-173\" srcset=\"https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105634-594x1024.jpg 594w, https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105634-174x300.jpg 174w, https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105634-768x1324.jpg 768w, https:\/\/www.stamping-fairies.de\/blog\/wp-content\/uploads\/2019\/04\/20190415_105634.jpg 953w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/figure>\n\n\n\n<p>Irgendwie\n fiel mir bei den Motiven sofort eine Wasserfallkarte ein. Habe ich \nschon ewig nicht mehr gemacht, aber hier war mir einfach danach.<\/p>\n\n\n\n<p>Auf  dem Wasserfallmechanismus habe ich dann vier Polaroids  aufgeklebt. Die neue Polaroidstanze war mir f\u00fcr meine Idee zu gro\u00df,  darum habe ich eine der Stanzen aus dem \u00e4lteren <a href=\"https:\/\/www.stamping-fairies.de\/stanzen-embossing-folder\/die-namics\/die-namics-precious-polaroids.html\">Perfect Polaroids  Stanzenset<\/a> daf\u00fcr benutzt. <\/p>\n\n\n\n<p>Hinter\n die Ausschnitte in den Polaroids kamen dann unterschiedliche Teile des \nHundemotivs. Die Motive in dem Set sind wirklich gro\u00df und so verwendet \nerinnern sie mich an die Fotos, die ich fr\u00fcher mit Freundinnen in diesen\n Fotost\u00e4nden gemacht habe. Jeder versuchte verzweifelt mit auf dem Bild \nzu sein&#8230;.<\/p>\n\n\n\n<p>Die Motive habe ich wieder in No-Lines Technik coloriert und einen zum roten Cardstock passenden Hintergrund dazugestaltet.<\/p>\n\n\n\n<p>Auf  das letzte Polaroid habe ich einen der Texte aus dem <a href=\"https:\/\/www.stamping-fairies.de\/montierte-stempel\/mft\/mft-easter-bunny.html\">Stempelset Easter  Bunny,<\/a> aufgeteilt auf drei Zeilen, wei\u00df aufembosst. Auf diesem Polaroid  habe ich auch noch ein kleines ausgestanztes Herz aufgeklebt.<\/p>\n\n\n\n<p>Unten auf den Tab, an dem gezogen werden muss, habe ich noch zwei der Worte aus dem <a href=\"https:\/\/www.stamping-fairies.de\/product_info.php?info=p19463_mft---interactive-labels.html\">Interactive Labels Stempelset<\/a> aufgestempelt.<\/p>\n\n\n\n<p> Von den einzelnen Polaroids habe ich keine Bilder gemacht, daf\u00fcr gibt es ein Video, in dem man sie auch gut erkennen kann: <\/p>\n\n\n\n<iframe loading=\"lazy\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" src=\"https:\/\/www.youtube.com\/embed\/L8aVqafuyQ4\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe>\n\n\n\n<p>Habt alle einen tollen Tag! Eure Kathrin<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo Ihr Lieben! Kennt Ihr die Picture Perfect Stempel aus dem April-Release von MFT? Die hatten es mir sofort angetan. Denn in diesem Set sind eben auch mal Tiere wie Hamster, Faultier, Affe. Trotzdem haben es auf meine zweite Karte mit dem Set die Hunde geschafft. Aus einem St\u00fcck schwarzem Cardstock, das ich etwas kleiner als meine wei\u00dfe Kartenbasis zugeschnitten habe, habe ich verteilt das #smile aus dem Stanzenset #Captions ausgestanzt und den Hintergrund dann mit rotem Cardstock hinterlegt. Da nur das rot ausgestanzte #smile ein wenig fad wirkte, habe ich dazwischen noch einige Male click mit wei\u00dfem Embossingpulver aufembosst. Daf\u00fcr habe ich einfach nur das letzte Wort eines der Texte aus dem Picture Perfect Set abgestempelt. Irgendwie fiel mir bei den Motiven sofort eine Wasserfallkarte ein. Habe ich schon ewig nicht mehr gemacht, aber hier war mir einfach danach. Auf dem Wasserfallmechanismus habe ich dann vier Polaroids aufgeklebt. Die neue Polaroidstanze war mir f\u00fcr meine Idee zu gro\u00df, darum habe ich eine der Stanzen aus dem \u00e4lteren Perfect Polaroids Stanzenset daf\u00fcr benutzt. Hinter die Ausschnitte in den Polaroids kamen dann unterschiedliche Teile des Hundemotivs. Die Motive in dem Set sind wirklich gro\u00df und so verwendet erinnern sie mich an die Fotos, die ich fr\u00fcher mit Freundinnen in diesen Fotost\u00e4nden gemacht habe. Jeder versuchte verzweifelt mit auf dem Bild zu sein&#8230;. Die Motive habe ich wieder in No-Lines Technik coloriert und einen zum roten Cardstock passenden Hintergrund dazugestaltet. Auf das letzte Polaroid habe ich einen der Texte aus dem Stempelset Easter Bunny, aufgeteilt auf drei Zeilen, wei\u00df aufembosst. Auf diesem Polaroid habe ich auch noch ein kleines ausgestanztes Herz aufgeklebt. Unten auf den Tab, an dem gezogen werden muss, habe ich noch zwei der Worte aus dem Interactive Labels Stempelset aufgestempelt. Von den einzelnen Polaroids habe ich keine Bilder gemacht, daf\u00fcr gibt es ein Video, in dem man sie auch gut erkennen kann: Habt alle einen tollen Tag! Eure Kathrin<\/p>\n","protected":false},"author":14,"featured_media":173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[61,7],"class_list":["post-171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-beitraege","tag-karte","tag-mftstamps"],"_links":{"self":[{"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/posts\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":2,"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/posts\/171\/revisions"}],"predecessor-version":[{"id":177,"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/posts\/171\/revisions\/177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/media\/173"}],"wp:attachment":[{"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/media?parent=171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/categories?post=171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stamping-fairies.de\/blog\/wp-json\/wp\/v2\/tags?post=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}